{"id":458,"date":"2024-04-26T17:09:11","date_gmt":"2024-04-26T08:09:11","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=458"},"modified":"2026-01-14T20:03:47","modified_gmt":"2026-01-14T11:03:47","slug":"%e5%8f%97%e4%bb%98%e3%81%91%e3%83%bb%e6%8e%a5%e5%ae%a2%e6%a5%ad%e5%8b%99%e3%80%80%e8%b2%a9%e5%a3%b2%e3%83%bb%e8%b2%b7%e5%8f%96%e3%82%a2%e3%83%89%e3%83%90%e3%82%a4%e3%82%b6%e3%83%bc%e3%80%80%e3%82%a8-4","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/458\/","title":{"rendered":"\u53d7\u4ed8\u3051\u30fb\u63a5\u5ba2\u696d\u52d9\u3000\u8ca9\u58f2\u30fb\u8cb7\u53d6\u30a2\u30c9\u30d0\u30a4\u30b6\u30fc\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u307f\u3088\u3057\u5e97 \/\u30b7\u30c6\u30a3\u30cd\u30c3\u30c8\u30fb\u30c8\u30e9\u30b9\u30c8\u682a\u5f0f\u4f1a\u793e"},"featured_media":460,"template":"","recruit":[2],"occupation":[6],"area":[34,24],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/458"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/460"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=458"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=458"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=458"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}