{"id":406,"date":"2024-03-22T16:43:18","date_gmt":"2024-03-22T07:43:18","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=406"},"modified":"2026-05-15T16:23:07","modified_gmt":"2026-05-15T07:23:07","slug":"%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3%e3%82%b0%e3%81%ae%e8%b2%b7%e5%8f%96%e5%96%b6%e6%a5%ad%e3%83%bb%e5%ba%97%e8%88%97%e3%82%b9%e3%82%bf%e3%83%83%e3%83%95%e3%80%80%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3-5","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/406\/","title":{"rendered":"\u30a8\u30b3\u30ea\u30f3\u30b0\u306e\u8cb7\u53d6\u55b6\u696d\u30fb\u5e97\u8217\u30b9\u30bf\u30c3\u30d5\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u7b95\u9762\u5e97\uff08\u962a\u6025\u96fb\u9244\u7b95\u9762\u7dda\uff09\uff0f\u682a\u5f0f\u4f1a\u793e\u30c6\u30eb\u30df\u30c3\u30af"},"featured_media":391,"template":"","recruit":[2],"occupation":[6],"area":[39,8],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/406"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/391"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=406"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=406"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=406"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}