{"id":317,"date":"2024-03-14T21:32:05","date_gmt":"2024-03-14T12:32:05","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=317"},"modified":"2026-05-22T15:52:51","modified_gmt":"2026-05-22T06:52:51","slug":"%e5%8f%97%e4%bb%98%e3%81%91%e3%83%bb%e6%8e%a5%e5%ae%a2%e6%a5%ad%e5%8b%99%e3%80%80%e8%b2%a9%e5%a3%b2%e3%83%bb%e8%b2%b7%e5%8f%96%e3%82%a2%e3%83%89%e3%83%90%e3%82%a4%e3%82%b6%e3%83%bc%e3%80%80%e3%82%a8-2","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/317\/","title":{"rendered":"\u53d7\u4ed8\u3051\u30fb\u63a5\u5ba2\u696d\u52d9\u3000\u8ca9\u58f2\u30fb\u8cb7\u53d6\u30a2\u30c9\u30d0\u30a4\u30b6\u30fc\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u6625\u65e5\u5e97\/\u682a\u5f0f\u4f1a\u793e\u30b9\u30c8\u30fc\u30f3"},"featured_media":239,"template":"","recruit":[2],"occupation":[6],"area":[23,52],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/317"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=317"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=317"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=317"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}