{"id":1056,"date":"2026-09-01T17:00:57","date_gmt":"2026-09-01T08:00:57","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=1056"},"modified":"2026-08-31T11:52:23","modified_gmt":"2026-08-31T02:52:23","slug":"%e3%83%96%e3%83%a9%e3%83%b3%e3%83%89%e5%93%81%e3%83%bb%e9%9b%91%e8%b2%a8%e7%ad%89%e3%81%ae%e9%91%91%e5%ae%9a%e5%a3%ab%e3%80%80%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3%e3%82%b0%e7%a6%8f%e5%b1%b1%e6%96%b0","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/1056\/","title":{"rendered":"\u30d6\u30e9\u30f3\u30c9\u54c1\u30fb\u96d1\u8ca8\u7b49\u306e\u9451\u5b9a\u58eb\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u798f\u5c71\u65b0\u6daf\u5e97\uff0f\u682a\u5f0f\u4f1a\u793e\u30a8\u30b3\u30df\u30eb\uff08\u30de\u30a8\u30c0\u30cf\u30a6\u30b8\u30f3\u30b0\uff09"},"featured_media":586,"template":"","recruit":[2],"occupation":[6],"area":[22,36],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/1056"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/586"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=1056"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=1056"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=1056"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=1056"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=1056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}