{"id":1054,"date":"2026-09-01T17:00:11","date_gmt":"2026-09-01T08:00:11","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=1054"},"modified":"2026-08-31T11:46:41","modified_gmt":"2026-08-31T02:46:41","slug":"%e8%b2%b7%e5%8f%96%e5%b0%82%e9%96%80%e5%ba%97%e3%81%a7%e3%81%ae%e6%8e%a5%e5%ae%a2%ef%bd%a5%e6%9f%bb%e5%ae%9astaff%e3%80%80%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3%e3%82%b0%e5%9f%8e%e9%99%bd%e5%ba%97","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/1054\/","title":{"rendered":"\u8cb7\u53d6\u5c02\u9580\u5e97\u3067\u306e\u63a5\u5ba2\uff65\u67fb\u5b9astaff\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u57ce\u967d\u5e97\uff0f\u4e09\u5bae\u5546\u4e8b\u682a\u5f0f\u4f1a\u793e"},"featured_media":446,"template":"","recruit":[2],"occupation":[6],"area":[45,8],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/1054"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/446"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=1054"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=1054"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=1054"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}