{"id":1031,"date":"2026-07-10T12:09:17","date_gmt":"2026-07-10T03:09:17","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=1031"},"modified":"2026-07-10T12:09:17","modified_gmt":"2026-07-10T03:09:17","slug":"%e3%83%96%e3%83%a9%e3%83%b3%e3%83%89%e5%93%81%e3%83%bb%e9%9b%91%e8%b2%a8%e7%ad%89%e3%81%ae%e9%91%91%e5%ae%9a%e5%a3%ab%e3%80%80%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3%e3%82%b0%e5%ae%88%e5%b1%b1%e5%ba%97j","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/1031\/","title":{"rendered":"\u30d6\u30e9\u30f3\u30c9\u54c1\u30fb\u96d1\u8ca8\u7b49\u306e\u9451\u5b9a\u58eb\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u5b88\u5c71\u5e97(JR\u7435\u7436\u6e56\u7dda)\uff0f\u682a\u5f0f\u4f1a\u793e\u30d1\u30e9\u30ec\u30eb"},"featured_media":238,"template":"","recruit":[2],"occupation":[6],"area":[48,8],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/1031"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/238"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=1031"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=1031"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=1031"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}