{"id":1018,"date":"2026-06-03T11:17:26","date_gmt":"2026-06-03T02:17:26","guid":{"rendered":"https:\/\/ecoring.co.jp\/recruit\/?post_type=recruitment&#038;p=1018"},"modified":"2026-06-03T11:17:26","modified_gmt":"2026-06-03T02:17:26","slug":"%e3%83%af%e3%83%bc%e3%82%af%e3%83%a9%e3%82%a4%e3%83%95%e3%83%90%e3%83%a9%e3%83%b3%e3%82%b9%e3%81%b0%e3%81%a3%e3%81%a1%e3%82%8a%e3%80%8e%e3%82%a8%e3%82%b3%e3%83%aa%e3%83%b3%e3%82%b0%e3%80%8f%e3%81%ae-8","status":"publish","type":"recruitment","link":"https:\/\/ecoring.co.jp\/recruit\/recruitment\/1018\/","title":{"rendered":"\u30ef\u30fc\u30af\u30e9\u30a4\u30d5\u30d0\u30e9\u30f3\u30b9\u3070\u3063\u3061\u308a\u300e\u30a8\u30b3\u30ea\u30f3\u30b0\u300f\u306e\u63a5\u5ba2\u30b9\u30bf\u30c3\u30d5\uff0a\u6b8b\u696d\u67086\u6642\u9593\u7a0b\u5ea6\u3000\u30a8\u30b3\u30ea\u30f3\u30b0\u5357\u4ed9\u53f0\u5e97\/\u682a\u5f0f\u4f1a\u793e\u30a6\u30a3\u30f3\u30e9\u30a4\u30ba"},"featured_media":239,"template":"","recruit":[2],"occupation":[6],"area":[49,27],"company":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment\/1018"}],"collection":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruitment"}],"about":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/types\/recruitment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"recruit","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/recruit?post=1018"},{"taxonomy":"occupation","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/occupation?post=1018"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/area?post=1018"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/ecoring.co.jp\/recruit\/wp-json\/wp\/v2\/company?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}